{"id":2661,"date":"2023-04-12T13:57:41","date_gmt":"2023-04-12T13:57:41","guid":{"rendered":"https:\/\/lex4.es\/?p=2661"},"modified":"2023-04-18T17:31:01","modified_gmt":"2023-04-18T17:31:01","slug":"impuestos","status":"publish","type":"post","link":"https:\/\/lex4.es\/es\/impuestos","title":{"rendered":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2661\" class=\"elementor elementor-2661\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97221ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97221ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfb3377\" data-id=\"bfb3377\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db4e155 elementor-widget elementor-widget-image\" data-id=\"db4e155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1512\" height=\"598\" src=\"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp\" class=\"attachment-full size-full wp-image-2686\" alt=\"Imagen sobre impuestos\" srcset=\"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp 1512w, https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img-300x119.webp 300w, https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img-1024x405.webp 1024w, https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img-768x304.webp 768w\" sizes=\"(max-width: 1512px) 100vw, 1512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e5bdf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e5bdf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-728d62c\" data-id=\"728d62c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa0495 elementor-widget elementor-widget-heading\" data-id=\"0fa0495\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfTiene una propiedad en Espa\u00f1a y reside fiscalmente en otro pa\u00eds?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7967297 elementor-widget elementor-widget-text-editor\" data-id=\"7967297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entonces es importante que conozca las obligaciones fiscales que tiene como propietario de una vivienda en Espa\u00f1a. Los no residentes est\u00e1n sujetos a una serie de impuestos que se aplican a la propiedad, tanto si la utilizan personal como si la alquilan.<\/p><p>A continuaci\u00f3n, presentamos una breve descripci\u00f3n de los impuestos que un propietario no residente debe pagar en Espa\u00f1a por ser propietario de una vivienda:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e66acf9 elementor-widget elementor-widget-heading\" data-id=\"e66acf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impuesto sobre la Renta de No Residentes (IRNR)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb2106 elementor-widget elementor-widget-text-editor\" data-id=\"8fb2106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El impuesto sobre la renta de no residentes (IRNR) es un impuesto que deben pagar los no residentes que obtienen ingresos en Espa\u00f1a. Este impuesto se aplica a los ingresos que provienen de actividades econ\u00f3micas realizadas en Espa\u00f1a, como el alquiler de propiedades o la venta de bienes.<\/p><p>Dependiendo del uso que usted le de a la vivienda estar\u00e1 obligado a presentar diferentes declaraciones.<\/p><p><strong><u>Si usted alquila su propiedad<\/u><\/strong>, tiene que presentar declaraciones trimestrales. Dependiendo de d\u00f3nde tenga su residencia fiscal el tipo de gravamen a aplicar ser\u00e1 del 19% o del 24%.<\/p><p>Si es residente fiscal en UE, Noruega o Islandia el impuesto a pagar ser\u00e1 el resultado de aplicar un 19% a la diferencia entre los ingresos y gastos.<\/p><p>Si es residente fiscal fuera de la UE, el impuesto a pagar ser\u00e1 el 24% de los ingresos.<\/p><p><strong><u>Si usted utiliza la vivienda para uso propio y no la alquila<\/u><\/strong>, tendr\u00e1 que presentar una declaraci\u00f3n anual. El tipo de gravamen que se aplica es del 19% para residentes en otro pa\u00eds europeo y ciudadanos de Noruega o Islandia y del 24% para resto de ciudadanos.\u00a0El importe de la declaraci\u00f3n anual ser\u00e1 el resultado de multiplicar el valor catastral de la vivienda por el 1,1% o 2% (dependiendo si el valor catastral ha sido revisado en los 10 ejercicios anteriores) y aplicar el tipo de gravamen anteriormente mencionado.<\/p><p><strong>En caso de que decida destinar la vivienda para uso propio y para alquiler, tendr\u00e1 que presentar ambas declaraciones<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb32639 elementor-widget elementor-widget-heading\" data-id=\"bb32639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impuesto sobre el Patrimonio (IP)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faa4361 elementor-widget elementor-widget-text-editor\" data-id=\"faa4361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El impuesto sobre el patrimonio (IP) es un impuesto que se aplica sobre el patrimonio neto de una persona. Este impuesto se aplica a los no residentes que poseen bienes en Espa\u00f1a con un valor superior a 700.000 euros. La tasa de impuesto sobre el patrimonio var\u00eda seg\u00fan la Comunidad Aut\u00f3noma en la que se encuentren los bienes, pero generalmente oscila entre el 0,2% y el 2,5%.<\/p><p>En algunas Comunidades Aut\u00f3nomas como Madrid y Andaluc\u00eda se ha eliminado este impuesto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6135704 elementor-widget elementor-widget-heading\" data-id=\"6135704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impuesto sobre Bienes Inmuebles (IBI)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd32bfc elementor-widget elementor-widget-text-editor\" data-id=\"bd32bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El IBI, o Impuesto sobre Bienes Inmuebles, es un impuesto que se aplica en Espa\u00f1a a la propiedad de bienes inmuebles, tales como viviendas, locales comerciales, terrenos y edificios. Es un impuesto municipal que grava la propiedad del bien inmueble y se utiliza para financiar los servicios p\u00fablicos locales, tales como la recogida de basura, el mantenimiento de parques y jardines, la limpieza de calles, entre otros.<\/p><p>El c\u00e1lculo del IBI se realiza en funci\u00f3n del valor catastral del bien inmueble, que es un valor establecido por la Administraci\u00f3n Tributaria y que se actualiza peri\u00f3dicamente. El tipo impositivo var\u00eda seg\u00fan el municipio y se aplica sobre el valor catastral del bien.<\/p><p>En general, el IBI se paga anualmente y el plazo para su pago puede variar seg\u00fan el municipio. Tambi\u00e9n es importante mencionar que existen algunas bonificaciones o exenciones del IBI para ciertos casos, como propiedades de inter\u00e9s cultural o de titularidad de organismos p\u00fablicos, entre otros<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df0c58c elementor-widget elementor-widget-heading\" data-id=\"df0c58c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tasa de recogida de basuras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f6eec1 elementor-widget elementor-widget-text-editor\" data-id=\"8f6eec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Es un impuesto local que se aplica en Espa\u00f1a para cubrir los gastos de los servicios de recogida, transporte y tratamiento de residuos s\u00f3lidos urbanos en un municipio. Esta tasa se incluye generalmente dentro del recibo del Impuesto sobre Bienes Inmuebles (IBI) y se paga anualmente.<\/p>\n<p>El importe de la tasa de recogida de basuras var\u00eda seg\u00fan el municipio, y suele estar basado en factores como el tama\u00f1o de la vivienda o del local, o el n\u00famero de personas empadronadas. Tambi\u00e9n puede haber diferentes tipos de tarifas seg\u00fan el uso del inmueble (residencial, comercial, industrial, etc.).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfTiene una propiedad en Espa\u00f1a y reside fiscalmente en otro pa\u00eds? Entonces es importante que conozca las obligaciones fiscales que tiene como propietario de una vivienda en Espa\u00f1a. Los no residentes est\u00e1n sujetos a una serie de impuestos que se aplican a la propiedad, tanto si la utilizan personal como si la alquilan. A continuaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[35],"tags":[],"class_list":["post-2661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impuestos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lex4.es\/es\/impuestos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lex4.es\/es\/impuestos\" \/>\n<meta property=\"og:site_name\" content=\"Lex4\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T13:57:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-18T17:31:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"lex4admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lex4admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos\"},\"author\":{\"name\":\"lex4admin\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es#\\\/schema\\\/person\\\/4b8fa3720d45bc4eb7b9584dcb0e49a4\"},\"headline\":\"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol\",\"datePublished\":\"2023-04-12T13:57:41+00:00\",\"dateModified\":\"2023-04-18T17:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos\"},\"wordCount\":724,\"publisher\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/impuestos-lex4-img.webp\",\"articleSection\":[\"Impuestos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos\",\"url\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos\",\"name\":\"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/impuestos-lex4-img.webp\",\"datePublished\":\"2023-04-12T13:57:41+00:00\",\"dateModified\":\"2023-04-18T17:31:01+00:00\",\"description\":\"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#primaryimage\",\"url\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/impuestos-lex4-img.webp\",\"contentUrl\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/impuestos-lex4-img.webp\",\"width\":1512,\"height\":598,\"caption\":\"Imagen sobre impuestos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es\\\/impuestos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lex4.es\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es#website\",\"url\":\"https:\\\/\\\/lex4.es\\\/es\",\"name\":\"Lex4\",\"description\":\"Solicitors Marbella\",\"publisher\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lex4.es\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es#organization\",\"name\":\"lex4\",\"url\":\"https:\\\/\\\/lex4.es\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/lex4-logo-web-verde.png\",\"contentUrl\":\"https:\\\/\\\/lex4.es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/lex4-logo-web-verde.png\",\"width\":350,\"height\":100,\"caption\":\"lex4\"},\"image\":{\"@id\":\"https:\\\/\\\/lex4.es\\\/es#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lex4.es\\\/es#\\\/schema\\\/person\\\/4b8fa3720d45bc4eb7b9584dcb0e49a4\",\"name\":\"lex4admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g\",\"caption\":\"lex4admin\"},\"sameAs\":[\"https:\\\/\\\/lex4.es\"],\"url\":\"https:\\\/\\\/lex4.es\\\/es\\\/author\\\/lex4admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol","description":"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lex4.es\/es\/impuestos","og_locale":"es_ES","og_type":"article","og_title":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol","og_description":"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.","og_url":"https:\/\/lex4.es\/es\/impuestos","og_site_name":"Lex4","article_published_time":"2023-04-12T13:57:41+00:00","article_modified_time":"2023-04-18T17:31:01+00:00","og_image":[{"width":1512,"height":598,"url":"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp","type":"image\/webp"}],"author":"lex4admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lex4admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lex4.es\/es\/impuestos#article","isPartOf":{"@id":"https:\/\/lex4.es\/es\/impuestos"},"author":{"name":"lex4admin","@id":"https:\/\/lex4.es\/es#\/schema\/person\/4b8fa3720d45bc4eb7b9584dcb0e49a4"},"headline":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol","datePublished":"2023-04-12T13:57:41+00:00","dateModified":"2023-04-18T17:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/lex4.es\/es\/impuestos"},"wordCount":724,"publisher":{"@id":"https:\/\/lex4.es\/es#organization"},"image":{"@id":"https:\/\/lex4.es\/es\/impuestos#primaryimage"},"thumbnailUrl":"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp","articleSection":["Impuestos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lex4.es\/es\/impuestos","url":"https:\/\/lex4.es\/es\/impuestos","name":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol","isPartOf":{"@id":"https:\/\/lex4.es\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/lex4.es\/es\/impuestos#primaryimage"},"image":{"@id":"https:\/\/lex4.es\/es\/impuestos#primaryimage"},"thumbnailUrl":"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp","datePublished":"2023-04-12T13:57:41+00:00","dateModified":"2023-04-18T17:31:01+00:00","description":"Todo sobre impuestos y obligaciones fiscales para no residentes en Espa\u00f1a que posean un inmueble en territorio espa\u00f1ol.","breadcrumb":{"@id":"https:\/\/lex4.es\/es\/impuestos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lex4.es\/es\/impuestos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lex4.es\/es\/impuestos#primaryimage","url":"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp","contentUrl":"https:\/\/lex4.es\/wp-content\/uploads\/2023\/04\/impuestos-lex4-img.webp","width":1512,"height":598,"caption":"Imagen sobre impuestos"},{"@type":"BreadcrumbList","@id":"https:\/\/lex4.es\/es\/impuestos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lex4.es\/es"},{"@type":"ListItem","position":2,"name":"Principales Impuestos en Espa\u00f1a para No Residentes con Inmuebles en Territorio Espa\u00f1ol"}]},{"@type":"WebSite","@id":"https:\/\/lex4.es\/es#website","url":"https:\/\/lex4.es\/es","name":"Lex4","description":"Solicitors Marbella","publisher":{"@id":"https:\/\/lex4.es\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lex4.es\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lex4.es\/es#organization","name":"lex4","url":"https:\/\/lex4.es\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lex4.es\/es#\/schema\/logo\/image\/","url":"https:\/\/lex4.es\/wp-content\/uploads\/2022\/01\/lex4-logo-web-verde.png","contentUrl":"https:\/\/lex4.es\/wp-content\/uploads\/2022\/01\/lex4-logo-web-verde.png","width":350,"height":100,"caption":"lex4"},"image":{"@id":"https:\/\/lex4.es\/es#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lex4.es\/es#\/schema\/person\/4b8fa3720d45bc4eb7b9584dcb0e49a4","name":"lex4admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9588f860c81cf2c20384d319c559f6563af4b0814c7ee87dbc5b1386df135e4f?s=96&d=mm&r=g","caption":"lex4admin"},"sameAs":["https:\/\/lex4.es"],"url":"https:\/\/lex4.es\/es\/author\/lex4admin"}]}},"_links":{"self":[{"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/posts\/2661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/comments?post=2661"}],"version-history":[{"count":40,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/posts\/2661\/revisions"}],"predecessor-version":[{"id":2765,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/posts\/2661\/revisions\/2765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/media\/2686"}],"wp:attachment":[{"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/media?parent=2661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/categories?post=2661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lex4.es\/es\/wp-json\/wp\/v2\/tags?post=2661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}